{"id":14696,"date":"2022-11-09T10:05:25","date_gmt":"2022-11-09T10:05:25","guid":{"rendered":"https:\/\/limakthermal.com\/atatuerk-und-yalova\/"},"modified":"2023-12-17T10:46:10","modified_gmt":"2023-12-17T10:46:10","slug":"atatuerk-und-yalova","status":"publish","type":"post","link":"https:\/\/limakthermal.com\/de\/atatuerk-und-yalova\/","title":{"rendered":"Atat\u00fcrk und Yalova"},"content":{"rendered":"<p><strong>Erster Besuch in Yalova<\/strong><br \/>\nAtat\u00fcrk besuchte Yalova zum ersten Mal am Montag, dem 19. August 1929, um 16.00 Uhr und wurde von der \u00d6ffentlichkeit mit gro\u00dfem Interesse empfangen. Er besuchte die hei\u00dfen Quellen und gab Anweisungen f\u00fcr die Verbesserung dieses Ortes. Er ging zum Baltac\u0131-Hof und k\u00fcmmerte sich um die Situation der dortigen Einwanderer. Am 20. August 1929 besuchte Atat\u00fcrk erneut Yalova, und am 21. August fuhr er \u00fcber Yalova nach Bursa.<br \/>\nAm Samstag, den 29. August, kam er erneut mit Ministerpr\u00e4sident \u0130smet \u0130n\u00f6n\u00fc nach Yalova. Danach wurde Yalova ein Ort, an dem Atat\u00fcrk seine Sommerarbeit verrichtete, sich ausruhte und wichtige Entscheidungen traf.<\/p>\n<p><strong>Umstrukturierte Yalova<\/strong><br \/>\nUnmittelbar nach seiner Entdeckung von Yalova (5 Tage) brachte Atat\u00fcrk etwa 400 Handwerker (Schmied, Elektriker, Tischler, Maurer) nach Yalova und mobilisierte sie f\u00fcr die Renovierung der Stadt. Er lie\u00df das Kursunlu-Thermalbad reparieren. Die Yalova-Thermalstra\u00dfe wird verbessert, die B\u00e4che Samanl\u0131 und Yalova werden gereinigt. Der erste Fl\u00e4chennutzungsplan von Yalova wird auf Anweisung von Atat\u00fcrk erstellt.<\/p>\n<p><strong>Er verbrachte 311 Tage in Yalova<\/strong><br \/>\nIn der Folgezeit besuchte er Yalova insgesamt 13 Mal. W\u00e4hrend seiner 27 st\u00e4ndigen Besuche hielt er sich 311 Tage und 273 N\u00e4chte in Yalova auf.<\/p>\n<p><strong>Er liebte Yalova sehr<\/strong><br \/>\nWenn er mit dem Zug von Ankara nach Istanbul fuhr, empfing er unterwegs Beamte und informierte sich \u00fcber die in Yalova durchgef\u00fchrten Arbeiten.<\/p>\n<p><strong>Er f\u00e4llte die wichtigsten Entscheidungen des Staates in Yalova<\/strong><br \/>\nW\u00e4hrend sich Yalova unter Atat\u00fcrks Aufmerksamkeit rasant entwickelte, empfing Atat\u00fcrk in Yalova in- und ausl\u00e4ndische Staatsm\u00e4nner und G\u00e4ste und traf hier viele der wichtigsten Entscheidungen des Staates. Er bereitete sich auf die Treffen in Yalova vor, denen er gro\u00dfe Bedeutung beimisst. Bei der Beschreibung von Atat\u00fcrks Arbeitspl\u00e4tzen war Yalova die am h\u00e4ufigsten genannte Stadt neben Istanbul.<\/p>\n<p><strong>Yalova wurde von einem Unterbezirk in einen Unfall umgewandelt und mit Istanbul verbunden<\/strong><br \/>\nKurz nach Atat\u00fcrks Ankunft in Yalova verwandelt sich Yalova von einem Stadtteil in einen Unfall. Sie ist dann mit Istanbul verbunden, das viel bessere Haushaltsm\u00f6glichkeiten hat.<\/p>\n<p><strong>Bewunderung f\u00fcr die Thermalquellen<\/strong><br \/>\nAtat\u00fcrk bewundert die Thermalquellen. Er ergriff sofort die Initiative, diesen Ort zu einem weltber\u00fchmten Zentrum zu machen. Eine Kommission aus angesehenen Pers\u00f6nlichkeiten Yalovas wird eingesetzt, um die hei\u00dfen Quellen von ihrem Betreiber zu \u00fcbernehmen. Der Preis wird durch eine Kommission bestimmt. Bei der Festsetzung des Preises wird darauf geachtet, dass der fr\u00fchere Betreiber nicht gesch\u00e4digt wird und die notwendige Zahlung an die Person erfolgt, die die Thermalquellen betreibt. Sadullah G\u00fcney, Generaldirektor von Seyr-i Sefain, wird zur bevollm\u00e4chtigten Person f\u00fcr die Reparatur und Renovierung von Termal ernannt. Waldwege werden in kurzer Zeit ge\u00f6ffnet. In den hei\u00dfen Quellen werden neue Warm- und Kaltwasserleitungen verlegt. Neue Wassertanks werden gebaut. Die Stra\u00dfe zwischen Termal und Yalova ist ausgebaut, und auf beiden Seiten der Stra\u00dfe sind Platanen gepflanzt. Es werden Gew\u00e4sser und Krankheiten untersucht, bei denen Gew\u00e4sser n\u00fctzlich sein k\u00f6nnen.<br \/>\nDank Atat\u00fcrk ist Termal zu einem der sch\u00f6nsten Orte der Welt f\u00fcr Gesundheit, Heilung, Natur und Erholung geworden. Man kann die Erinnerung an ATAT\u00dcRK auf jedem Stein dieses Zentrums sehen.<br \/>\nMeister Pandeli, der ber\u00fchmteste G\u00e4rtner der damaligen Zeit, wurde mit der Gestaltung des Gartens beauftragt. Meister Pandeli ist seit mehr als vierzig Jahren f\u00fcr Termal t\u00e4tig.<\/p>\n<div><strong>Pandeli Meisters Ansichten \u00fcber Atat\u00fcrks Ans\u00e4tze<\/strong><\/div>\n<ul>\n<li>Er interessierte sich sehr f\u00fcr Blumen. Sie liebte alle Blumen, sammelte Wildblumen und trug jeden Tag ein G\u00e4nsebl\u00fcmchen an ihrem Kragen. Sogar im Winter kam er und ging durch den Wald.<\/li>\n<li>Er unterhielt sich gerne mit Bauern, Arbeitern und Soldaten \u00fcber den Lebensunterhalt des Volkes und den Kurs der Verwaltung.<\/li>\n<li>Er h\u00f6rte sich gerne Probleme an und war f\u00fcr jeden n\u00fctzlich, und er sah jede Arbeit mit eigenen Augen.<\/li>\n<li>Er wusste nichts von Arroganz.<\/li>\n<li>Seine Anweisungen waren klar und pr\u00e4zise in den Werken, an die er glaubte.<\/li>\n<li>Er wusste, wie man Herzen gewinnt, ermutigt und sch\u00e4tzt.<\/li>\n<\/ul>\n<p>Der Aufwand f\u00fcr Thermik wird als D\u00e4mpfungsmaterial ausgewiesen. Da das Gewicht der gekauften Rohre zu hoch war, stellten die Finanzinspektoren, die den Generaldirektor von Seyr-i Sefain, Sadullah G\u00fcneyi, kontrollierten, fest, dass die Ausgaben nicht ordnungsgem\u00e4\u00df waren, und schlugen vor, Herrn Sadullah vor Gericht zu stellen. Atat\u00fcrk rief die Inspektoren nach \u00c7ankaya und er\u00f6rterte die Situation.<\/p>\n<p><strong>Inspektoren<\/strong><br \/>\n&#8222;Pascha, es ist gut. Niemand hat an der Ausgabestelle zum pers\u00f6nlichen Vorteil gearbeitet. Es wurden nur Ausgaben get\u00e4tigt, die gegen das Gesetz versto\u00dfen. Atat\u00fcrk sagte den Inspektoren;<br \/>\n&#8222;Schauen Sie sich die Arbeit und die geleistete Arbeit zusammen mit der Gesetzgebung an. Mit Ihrer Ansicht kann sich das Land nicht entwickeln. Da nicht f\u00fcr jedes Werk ein Gesetz gemacht werden kann, bleibt das Gute f\u00fcr das Land auf der Strecke. Wir sollten diejenigen, die sehr gut f\u00fcr das Land arbeiten, nicht beleidigen&#8220;.<\/p>\n<div><strong>Gr\u00fcnde f\u00fcr Atat\u00fcrks gro\u00dfes Interesse an Yalova<\/strong><\/div>\n<ul>\n<li>Natursch\u00f6nheiten und Heilwasser von Termal.<\/li>\n<li>Suche nach geeigneten Fl\u00e4chen in der Region f\u00fcr die Errichtung von Musterbetrieben.<\/li>\n<li>Die zentrale Lage in Bezug auf die Verkehrsanbindung.<\/li>\n<li>Die Ansiedlung von Einwanderern aus verschiedenen Regionen und die Schwierigkeiten, auf die sie in der Region stie\u00dfen.<\/li>\n<\/ul>\n<div><\/div>\n<div><strong>Atat\u00fcrks Aktivit\u00e4ten in Yalova<\/strong><\/div>\n<ul>\n<li>Bem\u00fchungen, Termal zu einem weltber\u00fchmten Gesundheitszentrum zu machen.<\/li>\n<li>Bau des Thermalen Atat\u00fcrk-Pavillons.<\/li>\n<li>Aufnahme des t\u00e4glichen F\u00e4hrdienstes von Istanbul nach Yalova.<\/li>\n<li>Yalova Thermal Hotel.<\/li>\n<li>Beginn der Malariabek\u00e4mpfung.<\/li>\n<li>Organisation des Layouts.<\/li>\n<li>\u00c7\u0131narl\u0131 h\u0131yaban, 12350 Meter lange und 10 Meter breite Stra\u00dfe mit dichtem Baumbestand auf beiden Seiten zwischen dem Yalova-Pier und dem Kurort.<\/li>\n<\/ul>\n<div><\/div>\n<div><strong>Wichtige Entscheidungen Atat\u00fcrks in Yalova<\/strong><\/div>\n<ul>\n<li>Die Bem\u00fchungen um die t\u00fcrkische Geschichte lange vor dem Islam, die historische Revolution keimte auf und nahm in Yalova Gestalt an.<\/li>\n<li>Die Umrisse der t\u00fcrkischen Geschichte wurden als Ergebnis der hier gef\u00fchrten Diskussionen gestaltet und in zwei B\u00e4nden ver\u00f6ffentlicht.<\/li>\n<li>Hier analysierte er pers\u00f6nlich die Geschichtsb\u00fccher in den Schulen und leitete sie an. Atat\u00fcrks Ansichten zu diesem Thema kommen in folgendem Satz zum Ausdruck: &#8222;Geschichte zu schreiben ist genauso wichtig wie Geschichte zu machen. Wenn derjenige, der schreibt, demjenigen, der tut, nicht treu ist, nimmt die unver\u00e4nderliche Wahrheit einen Charakter an, der die Menschheit verbl\u00fcfft&#8220;.<\/li>\n<li>Die T\u00fcrkische Historische Gesellschaft und die T\u00fcrkische Sprachgesellschaft wurden nach der Arbeit in Yalova gegr\u00fcndet.<\/li>\n<li>Die Freie Republikanische Partei, ein wichtiger Schritt in der Geschichte der t\u00fcrkischen Demokratie, wurde in Yalova gegr\u00fcndet. Zu diesem Zweck beauftragte er Herrn Fethi Okyar mit der Arbeit in Yalova.<\/li>\n<li>Er beschloss in Yalova, dass die technischen Schulen nicht geschlossen, sondern ausgebaut werden.<\/li>\n<\/ul>\n<div><\/div>\n<div><strong>Er war der erste Gast des Thermal Hotels<\/strong><\/div>\n<div>Atat\u00fcrk kam in der Nacht vom 21. auf den 22. Januar 1938 im Morgengrauen zum letzten Mal nach Yalova. Er war der erste Gast im neu erbauten Thermal Hotel. Sein Ziel war es, dass Termal in Yalova, das ihm sehr am Herzen lag, ein weltber\u00fchmtes Gesundheitszentrum wird. Er blieb 9 Tage lang hier. Am 1. Februar 1938 ging er nach Bursa, um einige Fabriken zu er\u00f6ffnen. Dies war das letzte Mal, dass Atat\u00fcrk Yalova verlie\u00df.<\/div>\n<div>Auch Yalova hat eine Entwicklung genommen, die des gro\u00dfen Interesses und der Liebe Atat\u00fcrks w\u00fcrdig ist, und hat sich zu einer gebildeten und modernen Stadt entwickelt.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Erster Besuch in Yalova Atat\u00fcrk besuchte Yalova zum ersten Mal am Montag, dem 19. August 1929, um 16.00 Uhr und wurde von der \u00d6ffentlichkeit mit gro\u00dfem Interesse empfangen. Er besuchte die hei\u00dfen Quellen und gab Anweisungen f\u00fcr die Verbesserung dieses Ortes. Er ging zum Baltac\u0131-Hof und k\u00fcmmerte sich um die Situation der dortigen Einwanderer. Am&hellip;&nbsp;<a href=\"https:\/\/limakthermal.com\/de\/atatuerk-und-yalova\/\" rel=\"bookmark\">Weiterlesen &raquo;<span class=\"screen-reader-text\">Atat\u00fcrk und Yalova<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":14871,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"off","neve_meta_content_width":70,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[300],"tags":[347,348,310],"class_list":["post-14696","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-yalova-de","tag-ataturk-de","tag-limak-de","tag-yalova-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Atat\u00fcrk und Yalova<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/limakthermal.com\/de\/atatuerk-und-yalova\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Atat\u00fcrk und Yalova\" \/>\n<meta property=\"og:description\" content=\"Erster Besuch in Yalova Atat\u00fcrk besuchte Yalova zum ersten Mal am Montag, dem 19. August 1929, um 16.00 Uhr und wurde von der \u00d6ffentlichkeit mit gro\u00dfem Interesse empfangen. Er besuchte die hei\u00dfen Quellen und gab Anweisungen f\u00fcr die Verbesserung dieses Ortes. Er ging zum Baltac\u0131-Hof und k\u00fcmmerte sich um die Situation der dortigen Einwanderer. Am&hellip;&nbsp;Weiterlesen &raquo;Atat\u00fcrk und Yalova\" \/>\n<meta property=\"og:url\" content=\"https:\/\/limakthermal.com\/de\/atatuerk-und-yalova\/\" \/>\n<meta property=\"og:site_name\" content=\"Limak Yalova Thermal Boutique Hotel\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/limaktermalotel\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-09T10:05:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-17T10:46:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/limakthermal.com\/wp-content\/uploads\/ataturkbuyukotel.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"563\" \/>\n\t<meta property=\"og:image:height\" content=\"419\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Limak Thermal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@limakthermal\" \/>\n<meta name=\"twitter:site\" content=\"@limakthermal\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Limak Thermal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/limakthermal.com\\\/de\\\/atatuerk-und-yalova\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/limakthermal.com\\\/de\\\/atatuerk-und-yalova\\\/\"},\"author\":{\"name\":\"Limak Thermal\",\"@id\":\"https:\\\/\\\/limakthermal.com\\\/de\\\/#\\\/schema\\\/person\\\/25733a9f267176579d4581ed03e556ba\"},\"headline\":\"Atat\u00fcrk und Yalova\",\"datePublished\":\"2022-11-09T10:05:25+00:00\",\"dateModified\":\"2023-12-17T10:46:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/limakthermal.com\\\/de\\\/atatuerk-und-yalova\\\/\"},\"wordCount\":1230,\"publisher\":{\"@id\":\"https:\\\/\\\/limakthermal.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/limakthermal.com\\\/de\\\/atatuerk-und-yalova\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/limakthermal.com\\\/wp-content\\\/uploads\\\/ataturkbuyukotel.jpg\",\"keywords\":[\"Atat\u00fcrk\",\"Limak\",\"Yalova\"],\"articleSection\":[\"Yalova\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/limakthermal.com\\\/de\\\/atatuerk-und-yalova\\\/\",\"url\":\"https:\\\/\\\/limakthermal.com\\\/de\\\/atatuerk-und-yalova\\\/\",\"name\":\"Atat\u00fcrk und Yalova\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/limakthermal.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/limakthermal.com\\\/de\\\/atatuerk-und-yalova\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/limakthermal.com\\\/de\\\/atatuerk-und-yalova\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/limakthermal.com\\\/wp-content\\\/uploads\\\/ataturkbuyukotel.jpg\",\"datePublished\":\"2022-11-09T10:05:25+00:00\",\"dateModified\":\"2023-12-17T10:46:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/limakthermal.com\\\/de\\\/atatuerk-und-yalova\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/limakthermal.com\\\/de\\\/atatuerk-und-yalova\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/limakthermal.com\\\/de\\\/atatuerk-und-yalova\\\/#primaryimage\",\"url\":\"https:\\\/\\\/limakthermal.com\\\/wp-content\\\/uploads\\\/ataturkbuyukotel.jpg\",\"contentUrl\":\"https:\\\/\\\/limakthermal.com\\\/wp-content\\\/uploads\\\/ataturkbuyukotel.jpg\",\"width\":563,\"height\":419},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/limakthermal.com\\\/de\\\/atatuerk-und-yalova\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Anasayfa\",\"item\":\"https:\\\/\\\/limakthermal.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Atat\u00fcrk und Yalova\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/limakthermal.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/limakthermal.com\\\/de\\\/\",\"name\":\"Limak Yalova Thermal Boutique Hotel\",\"description\":\"Warm Hospitality &amp; Excellent Service\",\"publisher\":{\"@id\":\"https:\\\/\\\/limakthermal.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/limakthermal.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/limakthermal.com\\\/de\\\/#organization\",\"name\":\"L\u0130MAK YALOVA THERMAL BOUTIQUE HOTEL\",\"url\":\"https:\\\/\\\/limakthermal.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/limakthermal.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/limakthermal.com\\\/wp-content\\\/uploads\\\/logolimakthermalyeni.png\",\"contentUrl\":\"https:\\\/\\\/limakthermal.com\\\/wp-content\\\/uploads\\\/logolimakthermalyeni.png\",\"width\":1795,\"height\":800,\"caption\":\"L\u0130MAK YALOVA THERMAL BOUTIQUE HOTEL\"},\"image\":{\"@id\":\"https:\\\/\\\/limakthermal.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/limaktermalotel\",\"https:\\\/\\\/x.com\\\/limakthermal\",\"https:\\\/\\\/instagram.com\\\/limakthermal\",\"https:\\\/\\\/tr.linkedin.com\\\/company\\\/limak-thermal-boutique-hotel\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/LimakHotels\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/limakthermal.com\\\/de\\\/#\\\/schema\\\/person\\\/25733a9f267176579d4581ed03e556ba\",\"name\":\"Limak Thermal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/limakthermal.com\\\/wp-content\\\/litespeed\\\/avatar\\\/d5b109fb10d11983643f8df317a948ef.jpg?ver=1783631975\",\"url\":\"https:\\\/\\\/limakthermal.com\\\/wp-content\\\/litespeed\\\/avatar\\\/d5b109fb10d11983643f8df317a948ef.jpg?ver=1783631975\",\"contentUrl\":\"https:\\\/\\\/limakthermal.com\\\/wp-content\\\/litespeed\\\/avatar\\\/d5b109fb10d11983643f8df317a948ef.jpg?ver=1783631975\",\"caption\":\"Limak Thermal\"},\"sameAs\":[\"https:\\\/\\\/limakthermal.com\"],\"url\":\"https:\\\/\\\/limakthermal.com\\\/de\\\/author\\\/limakthermal\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Atat\u00fcrk und Yalova","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/limakthermal.com\/de\/atatuerk-und-yalova\/","og_locale":"de_DE","og_type":"article","og_title":"Atat\u00fcrk und Yalova","og_description":"Erster Besuch in Yalova Atat\u00fcrk besuchte Yalova zum ersten Mal am Montag, dem 19. August 1929, um 16.00 Uhr und wurde von der \u00d6ffentlichkeit mit gro\u00dfem Interesse empfangen. Er besuchte die hei\u00dfen Quellen und gab Anweisungen f\u00fcr die Verbesserung dieses Ortes. Er ging zum Baltac\u0131-Hof und k\u00fcmmerte sich um die Situation der dortigen Einwanderer. Am&hellip;&nbsp;Weiterlesen &raquo;Atat\u00fcrk und Yalova","og_url":"https:\/\/limakthermal.com\/de\/atatuerk-und-yalova\/","og_site_name":"Limak Yalova Thermal Boutique Hotel","article_publisher":"https:\/\/facebook.com\/limaktermalotel","article_published_time":"2022-11-09T10:05:25+00:00","article_modified_time":"2023-12-17T10:46:10+00:00","og_image":[{"width":563,"height":419,"url":"https:\/\/limakthermal.com\/wp-content\/uploads\/ataturkbuyukotel.jpg","type":"image\/jpeg"}],"author":"Limak Thermal","twitter_card":"summary_large_image","twitter_creator":"@limakthermal","twitter_site":"@limakthermal","twitter_misc":{"Verfasst von":"Limak Thermal","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/limakthermal.com\/de\/atatuerk-und-yalova\/#article","isPartOf":{"@id":"https:\/\/limakthermal.com\/de\/atatuerk-und-yalova\/"},"author":{"name":"Limak Thermal","@id":"https:\/\/limakthermal.com\/de\/#\/schema\/person\/25733a9f267176579d4581ed03e556ba"},"headline":"Atat\u00fcrk und Yalova","datePublished":"2022-11-09T10:05:25+00:00","dateModified":"2023-12-17T10:46:10+00:00","mainEntityOfPage":{"@id":"https:\/\/limakthermal.com\/de\/atatuerk-und-yalova\/"},"wordCount":1230,"publisher":{"@id":"https:\/\/limakthermal.com\/de\/#organization"},"image":{"@id":"https:\/\/limakthermal.com\/de\/atatuerk-und-yalova\/#primaryimage"},"thumbnailUrl":"https:\/\/limakthermal.com\/wp-content\/uploads\/ataturkbuyukotel.jpg","keywords":["Atat\u00fcrk","Limak","Yalova"],"articleSection":["Yalova"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/limakthermal.com\/de\/atatuerk-und-yalova\/","url":"https:\/\/limakthermal.com\/de\/atatuerk-und-yalova\/","name":"Atat\u00fcrk und Yalova","isPartOf":{"@id":"https:\/\/limakthermal.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/limakthermal.com\/de\/atatuerk-und-yalova\/#primaryimage"},"image":{"@id":"https:\/\/limakthermal.com\/de\/atatuerk-und-yalova\/#primaryimage"},"thumbnailUrl":"https:\/\/limakthermal.com\/wp-content\/uploads\/ataturkbuyukotel.jpg","datePublished":"2022-11-09T10:05:25+00:00","dateModified":"2023-12-17T10:46:10+00:00","breadcrumb":{"@id":"https:\/\/limakthermal.com\/de\/atatuerk-und-yalova\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/limakthermal.com\/de\/atatuerk-und-yalova\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/limakthermal.com\/de\/atatuerk-und-yalova\/#primaryimage","url":"https:\/\/limakthermal.com\/wp-content\/uploads\/ataturkbuyukotel.jpg","contentUrl":"https:\/\/limakthermal.com\/wp-content\/uploads\/ataturkbuyukotel.jpg","width":563,"height":419},{"@type":"BreadcrumbList","@id":"https:\/\/limakthermal.com\/de\/atatuerk-und-yalova\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Anasayfa","item":"https:\/\/limakthermal.com\/de\/"},{"@type":"ListItem","position":2,"name":"Atat\u00fcrk und Yalova"}]},{"@type":"WebSite","@id":"https:\/\/limakthermal.com\/de\/#website","url":"https:\/\/limakthermal.com\/de\/","name":"Limak Yalova Thermal Boutique Hotel","description":"Warm Hospitality &amp; Excellent Service","publisher":{"@id":"https:\/\/limakthermal.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/limakthermal.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/limakthermal.com\/de\/#organization","name":"L\u0130MAK YALOVA THERMAL BOUTIQUE HOTEL","url":"https:\/\/limakthermal.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/limakthermal.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/limakthermal.com\/wp-content\/uploads\/logolimakthermalyeni.png","contentUrl":"https:\/\/limakthermal.com\/wp-content\/uploads\/logolimakthermalyeni.png","width":1795,"height":800,"caption":"L\u0130MAK YALOVA THERMAL BOUTIQUE HOTEL"},"image":{"@id":"https:\/\/limakthermal.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/limaktermalotel","https:\/\/x.com\/limakthermal","https:\/\/instagram.com\/limakthermal","https:\/\/tr.linkedin.com\/company\/limak-thermal-boutique-hotel","https:\/\/www.youtube.com\/user\/LimakHotels"]},{"@type":"Person","@id":"https:\/\/limakthermal.com\/de\/#\/schema\/person\/25733a9f267176579d4581ed03e556ba","name":"Limak Thermal","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/limakthermal.com\/wp-content\/litespeed\/avatar\/d5b109fb10d11983643f8df317a948ef.jpg?ver=1783631975","url":"https:\/\/limakthermal.com\/wp-content\/litespeed\/avatar\/d5b109fb10d11983643f8df317a948ef.jpg?ver=1783631975","contentUrl":"https:\/\/limakthermal.com\/wp-content\/litespeed\/avatar\/d5b109fb10d11983643f8df317a948ef.jpg?ver=1783631975","caption":"Limak Thermal"},"sameAs":["https:\/\/limakthermal.com"],"url":"https:\/\/limakthermal.com\/de\/author\/limakthermal\/"}]}},"jetpack_featured_media_url":"https:\/\/limakthermal.com\/wp-content\/uploads\/ataturkbuyukotel.jpg","jetpack-related-posts":[{"id":14581,"url":"https:\/\/limakthermal.com\/de\/yalova-wanderpavillon\/","url_meta":{"origin":14696,"position":0},"title":"Yalova Wanderpavillon","author":"Limak Thermal","date":"6. November 2022","format":false,"excerpt":"Gazi Mustafa Kemal Atat\u00fcrk kam 1927 erstmals nach Yalova und wohnte in einem Zelt auf dem Baltac\u0131-Hof, den er gekauft hatte. Mustafa Kemal Atat\u00fcrk, der die Stadt sehr liebte, kam am 21. August 1929 bei seinem Besuch in Bursa durch die Stadt, die er mehrmals besuchte. Bei seiner Ankunft in\u2026","rel":"","context":"In &quot;Orte zum Besuchen&quot;","block_context":{"text":"Orte zum Besuchen","link":"https:\/\/limakthermal.com\/de\/blog\/orte-zum-besuchen\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":11886,"url":"https:\/\/limakthermal.com\/de\/atatuerks-herrenhaus-thermal-yalova\/","url_meta":{"origin":14696,"position":1},"title":"Atat\u00fcrks Herrenhaus Thermal Yalova","author":"Limak Thermal","date":"20. November 2021","format":false,"excerpt":"Atat\u00fcrk \u00fcbernachtete zum ersten Mal in der Villa auf dem Bauernhof Baltac\u0131, als er nach Yalova kam. Dann wurde der Pavillon in Millet Farm gebaut. So entstand das Atat\u00fcrk Mansion , das zu diesen Villen geh\u00f6rt. Dieser Pavillon, der zu den ersten historischen Bauwerken der republikanischen \u00c4ra geh\u00f6rt, wurde 1929\u2026","rel":"","context":"In &quot;Orte zum Besuchen&quot;","block_context":{"text":"Orte zum Besuchen","link":"https:\/\/limakthermal.com\/de\/blog\/orte-zum-besuchen\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/limakthermal.com\/wp-content\/uploads\/2011\/07\/ataturkkoskutermal-jpg.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/limakthermal.com\/wp-content\/uploads\/2011\/07\/ataturkkoskutermal-jpg.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/limakthermal.com\/wp-content\/uploads\/2011\/07\/ataturkkoskutermal-jpg.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/limakthermal.com\/wp-content\/uploads\/2011\/07\/ataturkkoskutermal-jpg.webp?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/limakthermal.com\/wp-content\/uploads\/2011\/07\/ataturkkoskutermal-jpg.webp?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":14579,"url":"https:\/\/limakthermal.com\/de\/thermalquellen-von-yalova\/","url_meta":{"origin":14696,"position":2},"title":"Thermalquellen von Yalova","author":"Limak Thermal","date":"6. November 2022","format":false,"excerpt":"Die Thermalquellen von Yalova, die als einzige in der T\u00fcrkei eine Goldmedaille erhalten haben, sind seit mehr als 4000 Jahren in Betrieb und haben den Menschen Heilung verschafft. Der Thermalbezirk von Yalova, den der gro\u00dfe F\u00fchrer Mustafa Kemal Atat\u00fcrk mit den Worten ehrte: \"Dies wird die Wasserstadt der Zukunft sein\",\u2026","rel":"","context":"In &quot;Orte zum Besuchen&quot;","block_context":{"text":"Orte zum Besuchen","link":"https:\/\/limakthermal.com\/de\/blog\/orte-zum-besuchen\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/limakthermal.com\/wp-content\/uploads\/limaktermal-scaled.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/limakthermal.com\/wp-content\/uploads\/limaktermal-scaled.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/limakthermal.com\/wp-content\/uploads\/limaktermal-scaled.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/limakthermal.com\/wp-content\/uploads\/limaktermal-scaled.webp?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/limakthermal.com\/wp-content\/uploads\/limaktermal-scaled.webp?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/limakthermal.com\/wp-content\/uploads\/limaktermal-scaled.webp?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":16450,"url":"https:\/\/limakthermal.com\/de\/drei-schwestern-drei-heilige-yalova\/","url_meta":{"origin":14696,"position":3},"title":"Drei Schwestern&#8220;Drei Heilige&#8220; Yalova","author":"harunsahin","date":"17. September 2023","format":false,"excerpt":"In den B\u00fcchern mit dem Titel \"ACTA SANCTORUM\", die die heiligen religi\u00f6sen Ereignisse der Christen enthalten, wird ein Ereignis beschrieben, das in Yalova stattfand. Dem Glauben nach: Drei Schwestern namens Menodora, Metrodora und Nymphodora lebten in Bithynien (dem Gebiet, in dem sich das heutige Yalova befindet). Als sie das Alter\u2026","rel":"","context":"In &quot;Thermal&quot;","block_context":{"text":"Thermal","link":"https:\/\/limakthermal.com\/de\/blog\/thermal-de\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/limakthermal.com\/wp-content\/uploads\/uc_azize.webp?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":14590,"url":"https:\/\/limakthermal.com\/de\/suduesen-wasserfall-yalova-termal\/","url_meta":{"origin":14696,"position":4},"title":"Sud\u00fc\u015fen Wasserfall Yalova Termal","author":"Limak Thermal","date":"6. November 2022","format":false,"excerpt":"Der Sud\u00fc\u015fen-Wasserfall, einer der wertvollsten Teile von Yalova, befindet sich innerhalb der Grenzen des Bezirks Termal. Es ist sehr reizvoll, eine sch\u00f6ne Zeit mit wichtigen Menschen zu verbringen, die nur mit Ihnen inmitten einer nat\u00fcrlichen Sch\u00f6nheit sind. In den Picknickbereichen, die er seinen G\u00e4sten bietet, werden Sie feststellen, dass Ihre\u2026","rel":"","context":"In &quot;Orte zum Besuchen&quot;","block_context":{"text":"Orte zum Besuchen","link":"https:\/\/limakthermal.com\/de\/blog\/orte-zum-besuchen\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/limakthermal.com\/wp-content\/uploads\/2021\/07\/sudusenselales.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/limakthermal.com\/wp-content\/uploads\/2021\/07\/sudusenselales.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/limakthermal.com\/wp-content\/uploads\/2021\/07\/sudusenselales.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/limakthermal.com\/wp-content\/uploads\/2021\/07\/sudusenselales.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/limakthermal.com\/wp-content\/uploads\/2021\/07\/sudusenselales.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/limakthermal.com\/wp-content\/uploads\/2021\/07\/sudusenselales.png?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":14695,"url":"https:\/\/limakthermal.com\/de\/flitterwochen-hotel-in-yalova\/","url_meta":{"origin":14696,"position":5},"title":"Flitterwochen-Hotel in Yalova","author":"Limak Thermal","date":"9. November 2022","format":false,"excerpt":"Wie w\u00e4re es mit Flitterwochen in Yalova, das Atat\u00fcrk \"meine Stadt\" nannte? Sie haben sich f\u00fcr die Hochzeit entschieden. Termine wurden festgelegt, Veranstaltungsorte wurden recherchiert, Budgets wurden festgelegt, Sie kl\u00e4rten die Personen, die an Ihrer Hochzeit teilnehmen werden, Einladungen wurden gedruckt, Tischdekoration, St\u00fchle, Kerzenst\u00e4nder, Blumen, Farben, Hochzeitszeremonie, Trauzeugen usw. Die\u2026","rel":"","context":"In &quot;Yalova&quot;","block_context":{"text":"Yalova","link":"https:\/\/limakthermal.com\/de\/blog\/yalova-de\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/limakthermal.com\/wp-content\/uploads\/IMG_1642-scaled.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/limakthermal.com\/wp-content\/uploads\/IMG_1642-scaled.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/limakthermal.com\/wp-content\/uploads\/IMG_1642-scaled.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/limakthermal.com\/wp-content\/uploads\/IMG_1642-scaled.webp?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/limakthermal.com\/wp-content\/uploads\/IMG_1642-scaled.webp?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/limakthermal.com\/wp-content\/uploads\/IMG_1642-scaled.webp?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/limakthermal.com\/de\/wp-json\/wp\/v2\/posts\/14696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/limakthermal.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/limakthermal.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/limakthermal.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/limakthermal.com\/de\/wp-json\/wp\/v2\/comments?post=14696"}],"version-history":[{"count":0,"href":"https:\/\/limakthermal.com\/de\/wp-json\/wp\/v2\/posts\/14696\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/limakthermal.com\/de\/wp-json\/wp\/v2\/media\/14871"}],"wp:attachment":[{"href":"https:\/\/limakthermal.com\/de\/wp-json\/wp\/v2\/media?parent=14696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/limakthermal.com\/de\/wp-json\/wp\/v2\/categories?post=14696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/limakthermal.com\/de\/wp-json\/wp\/v2\/tags?post=14696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}